{"id":24,"date":"2023-07-18T18:17:30","date_gmt":"2023-07-18T17:17:30","guid":{"rendered":"https:\/\/inasalrepublic.ph\/?page_id=24"},"modified":"2023-07-31T08:04:57","modified_gmt":"2023-07-31T07:04:57","slug":"home","status":"publish","type":"page","link":"https:\/\/inasalrepublic.ph\/","title":{"rendered":"Home"},"content":{"rendered":"<div class=\"wp-block-group slider-for-desktop\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><\/div><\/div><div class=\"wp-block-group slider-for-mobile\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><\/div><\/div><div class=\"wp-block-columns content-row is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"300\" src=\"http:\/\/inasalrepublic.ph\/wp-content\/uploads\/2023\/07\/desserts.png\" alt=\"desserts\" class=\"wp-image-179\" srcset=\"https:\/\/inasalrepublic.ph\/wp-content\/uploads\/2023\/07\/desserts.png 800w, https:\/\/inasalrepublic.ph\/wp-content\/uploads\/2023\/07\/desserts-300x113.png 300w, https:\/\/inasalrepublic.ph\/wp-content\/uploads\/2023\/07\/desserts-768x288.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"300\" src=\"http:\/\/inasalrepublic.ph\/wp-content\/uploads\/2023\/07\/inihaw.png\" alt=\"inihaw\" class=\"wp-image-181\" srcset=\"https:\/\/inasalrepublic.ph\/wp-content\/uploads\/2023\/07\/inihaw.png 800w, https:\/\/inasalrepublic.ph\/wp-content\/uploads\/2023\/07\/inihaw-300x113.png 300w, https:\/\/inasalrepublic.ph\/wp-content\/uploads\/2023\/07\/inihaw-768x288.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/inasalrepublic.ph\/index.php\/wp-json\/wp\/v2\/pages\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inasalrepublic.ph\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/inasalrepublic.ph\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/inasalrepublic.ph\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inasalrepublic.ph\/index.php\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":10,"href":"https:\/\/inasalrepublic.ph\/index.php\/wp-json\/wp\/v2\/pages\/24\/revisions"}],"predecessor-version":[{"id":205,"href":"https:\/\/inasalrepublic.ph\/index.php\/wp-json\/wp\/v2\/pages\/24\/revisions\/205"}],"wp:attachment":[{"href":"https:\/\/inasalrepublic.ph\/index.php\/wp-json\/wp\/v2\/media?parent=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}